{"id":1922,"date":"2022-01-26T13:53:13","date_gmt":"2022-01-26T13:53:13","guid":{"rendered":"https:\/\/hotelbeltramonto.it\/offers\/"},"modified":"2026-03-11T11:50:11","modified_gmt":"2026-03-11T11:50:11","slug":"offers","status":"publish","type":"page","link":"https:\/\/hotelbeltramonto.it\/en\/offers\/","title":{"rendered":"Offers"},"content":{"rendered":"<p>[et_pb_section fb_built=&#8221;1&#8243; bg_img_2=&#8221;https:\/\/hotelbeltramonto.it\/wp-content\/uploads\/resort-02.jpg&#8221; use_background_color_gradient_2=&#8221;off&#8221; background_color_gradient_direction_2=&#8221;105deg&#8221; background_color_gradient_stops_2=&#8221;rgba(255,255,255,0.65) 0%|rgba(255,255,255,0) 76%&#8221; background_color_gradient_start_2=&#8221;rgba(255,255,255,0.65)&#8221; background_color_gradient_end_2=&#8221;rgba(255,255,255,0)&#8221; background_color_gradient_start_position_2=&#8221;0%&#8221; background_color_gradient_end_position_2=&#8221;76%&#8221; background_color_gradient_overlays_image_2=&#8221;on&#8221; admin_label=&#8221;Header&#8221; _builder_version=&#8221;4.19.0&#8243; background_image=&#8221;https:\/\/hotelbeltramonto.it\/wp-content\/uploads\/BEL-TRAMONTO_2024_008-1-1.jpg&#8221; vertical_offset_tablet=&#8221;0&#8243; horizontal_offset_tablet=&#8221;0&#8243; custom_padding=&#8221;20vw|0px|0|0px|false|false&#8221; box_shadow_horizontal_tablet=&#8221;0px&#8221; box_shadow_vertical_tablet=&#8221;0px&#8221; box_shadow_blur_tablet=&#8221;40px&#8221; box_shadow_spread_tablet=&#8221;0px&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_row custom_padding_last_edited=&#8221;on|desktop&#8221; _builder_version=&#8221;4.19.0&#8243; background_color=&#8221;#ffffff&#8221; max_width=&#8221;1160px&#8221; custom_padding=&#8221;|40px||40px||true&#8221; custom_padding_tablet=&#8221;|20px||20px||true&#8221; custom_padding_phone=&#8221;&#8221; use_custom_width=&#8221;on&#8221; custom_width_px=&#8221;1160px&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.16&#8243; custom_padding=&#8221;|||&#8221; global_colors_info=&#8221;{}&#8221; custom_padding__hover=&#8221;|||&#8221;][et_pb_text _builder_version=&#8221;4.19.0&#8243; vertical_offset_tablet=&#8221;0&#8243; horizontal_offset_tablet=&#8221;0&#8243; z_index_tablet=&#8221;0&#8243; text_text_shadow_horizontal_length_tablet=&#8221;0px&#8221; text_text_shadow_vertical_length_tablet=&#8221;0px&#8221; text_text_shadow_blur_strength_tablet=&#8221;1px&#8221; link_text_shadow_horizontal_length_tablet=&#8221;0px&#8221; link_text_shadow_vertical_length_tablet=&#8221;0px&#8221; link_text_shadow_blur_strength_tablet=&#8221;1px&#8221; ul_text_shadow_horizontal_length_tablet=&#8221;0px&#8221; ul_text_shadow_vertical_length_tablet=&#8221;0px&#8221; ul_text_shadow_blur_strength_tablet=&#8221;1px&#8221; ol_text_shadow_horizontal_length_tablet=&#8221;0px&#8221; ol_text_shadow_vertical_length_tablet=&#8221;0px&#8221; ol_text_shadow_blur_strength_tablet=&#8221;1px&#8221; quote_text_shadow_horizontal_length_tablet=&#8221;0px&#8221; quote_text_shadow_vertical_length_tablet=&#8221;0px&#8221; quote_text_shadow_blur_strength_tablet=&#8221;1px&#8221; header_text_shadow_horizontal_length_tablet=&#8221;0px&#8221; header_text_shadow_vertical_length_tablet=&#8221;0px&#8221; header_text_shadow_blur_strength_tablet=&#8221;1px&#8221; header_2_text_shadow_horizontal_length_tablet=&#8221;0px&#8221; header_2_text_shadow_vertical_length_tablet=&#8221;0px&#8221; header_2_text_shadow_blur_strength_tablet=&#8221;1px&#8221; header_3_text_shadow_horizontal_length_tablet=&#8221;0px&#8221; header_3_text_shadow_vertical_length_tablet=&#8221;0px&#8221; header_3_text_shadow_blur_strength_tablet=&#8221;1px&#8221; header_4_text_shadow_horizontal_length_tablet=&#8221;0px&#8221; header_4_text_shadow_vertical_length_tablet=&#8221;0px&#8221; header_4_text_shadow_blur_strength_tablet=&#8221;1px&#8221; header_5_text_shadow_horizontal_length_tablet=&#8221;0px&#8221; header_5_text_shadow_vertical_length_tablet=&#8221;0px&#8221; header_5_text_shadow_blur_strength_tablet=&#8221;1px&#8221; header_6_text_shadow_horizontal_length_tablet=&#8221;0px&#8221; header_6_text_shadow_vertical_length_tablet=&#8221;0px&#8221; header_6_text_shadow_blur_strength_tablet=&#8221;1px&#8221; box_shadow_horizontal_tablet=&#8221;0px&#8221; box_shadow_vertical_tablet=&#8221;0px&#8221; box_shadow_blur_tablet=&#8221;40px&#8221; box_shadow_spread_tablet=&#8221;0px&#8221; locked=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221; header_3_text_shadow_style__hover=&#8221;none&#8221; header_3_text_shadow_style__hover_enabled=&#8221;none&#8221;]<\/p>\n<h1>Discover our<\/h1>\n<h1>Offers<\/h1>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=&#8221;1&#8243; theme_builder_area=&#8221;post_content&#8221; _builder_version=&#8221;4.19.0&#8243; _module_preset=&#8221;default&#8221;][et_pb_row _builder_version=&#8221;4.19.0&#8243; _module_preset=&#8221;default&#8221; theme_builder_area=&#8221;post_content&#8221; hover_enabled=&#8221;0&#8243; sticky_enabled=&#8221;0&#8243; border_color_bottom=&#8221;#0C71C3&#8243; border_width_bottom=&#8221;1px&#8221;][et_pb_column _builder_version=&#8221;4.19.0&#8243; _module_preset=&#8221;default&#8221; type=&#8221;4_4&#8243; theme_builder_area=&#8221;post_content&#8221;][et_pb_blog _builder_version=&#8221;4.19.0&#8243; _module_preset=&#8221;default&#8221; theme_builder_area=&#8221;post_content&#8221; include_categories=&#8221;19,current&#8221; show_content=&#8221;on&#8221; hover_enabled=&#8221;0&#8243; sticky_enabled=&#8221;0&#8243; border_width_bottom_fullwidth=&#8221;2px&#8221; border_color_bottom_fullwidth=&#8221;#0C71C3&#8243;][\/et_pb_blog][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=&#8221;1&#8243; _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;default&#8221; custom_padding=&#8221;1px|||||&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_row _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_text _builder_version=&#8221;4.19.0&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<p>\n<script>\nfunction show_form(){\ndocument.getElementById('separator').scrollIntoView();\n}\n<\/script>\n<\/p>\n\n<div class=\"wpcf7 no-js\" id=\"wpcf7-f832-o1\" lang=\"it-IT\" dir=\"ltr\" data-wpcf7-id=\"832\">\n<div class=\"screen-reader-response\"><p role=\"status\" aria-live=\"polite\" aria-atomic=\"true\"><\/p> <ul><\/ul><\/div>\n<form action=\"\/en\/wp-json\/wp\/v2\/pages\/1922#wpcf7-f832-o1\" method=\"post\" class=\"wpcf7-form init\" aria-label=\"Modulo di contatto\" novalidate=\"novalidate\" data-status=\"init\">\n<fieldset class=\"hidden-fields-container\"><input type=\"hidden\" name=\"_wpcf7\" value=\"832\" \/><input type=\"hidden\" name=\"_wpcf7_version\" value=\"6.1\" \/><input type=\"hidden\" name=\"_wpcf7_locale\" value=\"it_IT\" \/><input type=\"hidden\" name=\"_wpcf7_unit_tag\" value=\"wpcf7-f832-o1\" \/><input type=\"hidden\" name=\"_wpcf7_container_post\" value=\"0\" \/><input type=\"hidden\" name=\"_wpcf7_posted_data_hash\" value=\"\" \/>\n<\/fieldset>\n<style>\n\n.btn {\n background-color: #0077cc;\n border: none;\n color: white;\n padding: 20px;\n text-align: center;\n text-decoration: none;\n display: inline-block;\n font-size: 16px;\n margin: 4px 2px;\n cursor: pointer;\n border-radius: 8px;\n}\n.wpcf7-spinner{display:none;}\n.form-control {\n display: block;\n width: 100%;\n padding: 0.375rem 0.75rem;\n font-size: 1rem;\n line-height: 1.5;\n color: #495057;\n background-color: #fff;\n background-clip: padding-box;\n border: 1px solid #ced4da;\n border-radius: 0.25rem;\n transition: border-color .15s ease-in-out,box-shadow .15s ease-in-out;\n}.row::after {content: \"\";clear: both;display: table;}[class*=\"col-\"] {float: left;padding: 15px;}.col-6 {width: 50%;}.col-12 {width: 100%;}@media screen and (max-width: 600px) {.col-6 {width: 100%;} }\n<\/style>\n<div id=\"form-container\">\n\t<h3>Compila il form\n\t<\/h3>\n\t<div class=\"row\">\n\t\t<div class=\"col-6\">\n\t\t\t<p><label> Data di arrivo <\/label><br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"date-arrivo\"><input class=\"wpcf7-form-control wpcf7-date wpcf7-validates-as-required wpcf7-validates-as-date form-control\" aria-required=\"true\" aria-invalid=\"false\" value=\"\" type=\"date\" name=\"date-arrivo\" \/><\/span>\n\t\t\t<\/p>\n\t\t<\/div>\n\t\t<div class=\"col-6\">\n\t\t\t<p><label> Data di partenza <\/label><br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"date-partenza\"><input class=\"wpcf7-form-control wpcf7-date wpcf7-validates-as-required wpcf7-validates-as-date form-control\" aria-required=\"true\" aria-invalid=\"false\" value=\"\" type=\"date\" name=\"date-partenza\" \/><\/span>\n\t\t\t<\/p>\n\t\t<\/div>\n\t\t<div class=\"col-6\">\n\t\t\t<p><label> Adulti <\/label><br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"number-adulti\"><input class=\"wpcf7-form-control wpcf7-number wpcf7-validates-as-required wpcf7-validates-as-number form-control\" aria-required=\"true\" aria-invalid=\"false\" value=\"2\" type=\"number\" name=\"number-adulti\" \/><\/span>\n\t\t\t<\/p>\n\t\t<\/div>\n\t\t<div class=\"col-6\">\n\t\t\t<p><label> Bambini <\/label><br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"number-bambini\"><input class=\"wpcf7-form-control wpcf7-number wpcf7-validates-as-number form-control\" aria-invalid=\"false\" value=\"\" type=\"number\" name=\"number-bambini\" \/><\/span>\n\t\t\t<\/p>\n\t\t<\/div>\n\t\t<div class=\"col-6\">\n\t\t\t<p><label> Trattamento <\/label><br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"menu-trattamento\"><select class=\"wpcf7-form-control wpcf7-select form-control\" aria-invalid=\"false\" name=\"menu-trattamento\"><option value=\"Bed &amp; Breakfast\">Bed &amp; Breakfast<\/option><option value=\"Mezza Pensione\">Mezza Pensione<\/option><option value=\"Pensione Completa\">Pensione Completa<\/option><\/select><\/span>\n\t\t\t<\/p>\n\t\t<\/div>\n\t<\/div>\n\t<div class=\"row\" style=\"padding-top:40px\">\n\t\t<div class=\"col-12\">\n\t\t\t<h3>Dati del referente\n\t\t\t<\/h3>\n\t\t<\/div>\n\t\t<div class=\"col-6\">\n\t\t\t<p><label> Il tuo nome <\/label><br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"your-name\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required form-control\" aria-required=\"true\" aria-invalid=\"false\" value=\"\" type=\"text\" name=\"your-name\" \/><\/span>\n\t\t\t<\/p>\n\t\t<\/div>\n\t\t<div class=\"col-6\">\n\t\t\t<p><label> Il tuo cognome <\/label><br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"your-surname\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required form-control\" aria-required=\"true\" aria-invalid=\"false\" value=\"\" type=\"text\" name=\"your-surname\" \/><\/span>\n\t\t\t<\/p>\n\t\t<\/div>\n\t\t<div class=\"col-6\">\n\t\t\t<p><label> La tua email <\/label><br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"your-email\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-email wpcf7-validates-as-required wpcf7-text wpcf7-validates-as-email form-control\" aria-required=\"true\" aria-invalid=\"false\" value=\"\" type=\"email\" name=\"your-email\" \/><\/span>\n\t\t\t<\/p>\n\t\t<\/div>\n\t\t<div class=\"col-6\">\n\t\t\t<p><label> Il tuo telefono <\/label><br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"tel-personale\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-tel wpcf7-validates-as-required wpcf7-text wpcf7-validates-as-tel form-control\" aria-required=\"true\" aria-invalid=\"false\" value=\"\" type=\"tel\" name=\"tel-personale\" \/><\/span>\n\t\t\t<\/p>\n\t\t<\/div>\n\t\t<div class=\"col-12\">\n\t\t\t<p><label> Il tuo messaggio (facoltativo) <\/label><br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"your-message\"><textarea cols=\"40\" rows=\"10\" maxlength=\"2000\" class=\"wpcf7-form-control wpcf7-textarea form-control\" aria-invalid=\"false\" name=\"your-message\"><\/textarea><\/span>\n\t\t\t<\/p>\n\t\t<\/div>\n\t\t<div class=\"col-12\" style=\"text-align:right\">\n\t\t\t<p><span class=\"wpcf7-form-control-wrap\" data-name=\"acceptance-privacy\"><span class=\"wpcf7-form-control wpcf7-acceptance\"><span class=\"wpcf7-list-item\"><label><input type=\"checkbox\" name=\"acceptance-privacy\" value=\"1\" aria-invalid=\"false\" \/><span class=\"wpcf7-list-item-label\">Ho letto e accetto la <a href=\"https:\/\/hotelbeltramonto.it\/privacy-policy\">Privacy Policy<\/a><\/span><\/label><\/span><\/span><\/span><br \/>\n<div class=\"cf7-cf-turnstile\" style=\"margin-top: 0px; margin-bottom: -15px;\"> <div id=\"cf-turnstile-cf7-1449776948\" class=\"cf-turnstile\" data-callback=\"turnstileCF7Callback\" data-sitekey=\"0x4AAAAAABV01mW2zJHzJXWz\" data-theme=\"light\" data-language=\"auto\" data-size=\"normal\" data-retry=\"auto\" data-retry-interval=\"1000\" data-action=\"contact-form-7\" data-appearance=\"always\"><\/div> <style>.wpcf7-submit { pointer-events: none; opacity: 0.5; }<\/style> <script>document.addEventListener(\"DOMContentLoaded\", function() { setTimeout(function(){ var e=document.getElementById(\"cf-turnstile-cf7-1449776948\"); e&&!e.innerHTML.trim()&&(turnstile.remove(\"#cf-turnstile-cf7-1449776948\"), turnstile.render(\"#cf-turnstile-cf7-1449776948\", {sitekey:\"0x4AAAAAABV01mW2zJHzJXWz\"})); }, 0); });<\/script> <br class=\"cf-turnstile-br cf-turnstile-br-cf7-1449776948\"> <style>#cf-turnstile-cf7-1449776948 { margin-left: -15px; }<\/style> <script>document.addEventListener(\"DOMContentLoaded\",function(){document.querySelectorAll('.wpcf7-form').forEach(function(e){e.addEventListener('submit',function(){if(document.getElementById('cf-turnstile-cf7-1449776948')){setTimeout(function(){turnstile.reset('#cf-turnstile-cf7-1449776948');},1000)}})})});<\/script> <\/div><br\/><input class=\"wpcf7-form-control wpcf7-submit has-spinner btn\" type=\"submit\" value=\"Invia\" \/>\n\t\t\t<\/p>\n\t\t<\/div>\n\t<\/div>\n<\/div><div class=\"wpcf7-response-output\" aria-hidden=\"true\"><\/div>\n<\/form>\n<\/div>\n\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][\/et_pb_section]<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Discover our Offers \n<div class=\"wpcf7 no-js\" id=\"wpcf7-f832-o2\" lang=\"it-IT\" dir=\"ltr\" data-wpcf7-id=\"832\">\n<div class=\"screen-reader-response\"><p role=\"status\" aria-live=\"polite\" aria-atomic=\"true\"><\/p> <ul><\/ul><\/div>\n<form action=\"\/en\/wp-json\/wp\/v2\/pages\/1922#wpcf7-f832-o2\" method=\"post\" class=\"wpcf7-form init\" aria-label=\"Modulo di contatto\" novalidate=\"novalidate\" data-status=\"init\">\n<fieldset class=\"hidden-fields-container\"><input type=\"hidden\" name=\"_wpcf7\" value=\"832\" \/><input type=\"hidden\" name=\"_wpcf7_version\" value=\"6.1\" \/><input type=\"hidden\" name=\"_wpcf7_locale\" value=\"it_IT\" \/><input type=\"hidden\" name=\"_wpcf7_unit_tag\" value=\"wpcf7-f832-o2\" \/><input type=\"hidden\" name=\"_wpcf7_container_post\" value=\"0\" \/><input type=\"hidden\" name=\"_wpcf7_posted_data_hash\" value=\"\" \/>\n<\/fieldset>\n<style>\n\n.btn {\n background-color: #0077cc;\n border: none;\n color: white;\n padding: 20px;\n text-align: center;\n text-decoration: none;\n display: inline-block;\n font-size: 16px;\n margin: 4px 2px;\n cursor: pointer;\n border-radius: 8px;\n}\n.wpcf7-spinner{display:none;}\n.form-control {\n display: block;\n width: 100%;\n padding: 0.375rem 0.75rem;\n font-size: 1rem;\n line-height: 1.5;\n color: #495057;\n background-color: #fff;\n background-clip: padding-box;\n border: 1px solid #ced4da;\n border-radius: 0.25rem;\n transition: border-color .15s ease-in-out,box-shadow .15s ease-in-out;\n}.row::after {content: \"\";clear: both;display: table;}[class*=\"col-\"] {float: left;padding: 15px;}.col-6 {width: 50%;}.col-12 {width: 100%;}@media screen and (max-width: 600px) {.col-6 {width: 100%;} }\n<\/style>\n<div id=\"form-container\">\n\t<h3>Compila il form\n\t<\/h3>\n\t<div class=\"row\">\n\t\t<div class=\"col-6\">\n\t\t\t<p><label> Data di arrivo <\/label><br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"date-arrivo\"><input class=\"wpcf7-form-control wpcf7-date wpcf7-validates-as-required wpcf7-validates-as-date form-control\" aria-required=\"true\" aria-invalid=\"false\" value=\"\" type=\"date\" name=\"date-arrivo\" \/><\/span>\n\t\t\t<\/p>\n\t\t<\/div>\n\t\t<div class=\"col-6\">\n\t\t\t<p><label> Data di partenza <\/label><br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"date-partenza\"><input class=\"wpcf7-form-control wpcf7-date wpcf7-validates-as-required wpcf7-validates-as-date form-control\" aria-required=\"true\" aria-invalid=\"false\" value=\"\" type=\"date\" name=\"date-partenza\" \/><\/span>\n\t\t\t<\/p>\n\t\t<\/div>\n\t\t<div class=\"col-6\">\n\t\t\t<p><label> Adulti <\/label><br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"number-adulti\"><input class=\"wpcf7-form-control wpcf7-number wpcf7-validates-as-required wpcf7-validates-as-number form-control\" aria-required=\"true\" aria-invalid=\"false\" value=\"2\" type=\"number\" name=\"number-adulti\" \/><\/span>\n\t\t\t<\/p>\n\t\t<\/div>\n\t\t<div class=\"col-6\">\n\t\t\t<p><label> Bambini <\/label><br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"number-bambini\"><input class=\"wpcf7-form-control wpcf7-number wpcf7-validates-as-number form-control\" aria-invalid=\"false\" value=\"\" type=\"number\" name=\"number-bambini\" \/><\/span>\n\t\t\t<\/p>\n\t\t<\/div>\n\t\t<div class=\"col-6\">\n\t\t\t<p><label> Trattamento <\/label><br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"menu-trattamento\"><select class=\"wpcf7-form-control wpcf7-select form-control\" aria-invalid=\"false\" name=\"menu-trattamento\"><option value=\"Bed &amp; Breakfast\">Bed &amp; Breakfast<\/option><option value=\"Mezza Pensione\">Mezza Pensione<\/option><option value=\"Pensione Completa\">Pensione Completa<\/option><\/select><\/span>\n\t\t\t<\/p>\n\t\t<\/div>\n\t<\/div>\n\t<div class=\"row\" style=\"padding-top:40px\">\n\t\t<div class=\"col-12\">\n\t\t\t<h3>Dati del referente\n\t\t\t<\/h3>\n\t\t<\/div>\n\t\t<div class=\"col-6\">\n\t\t\t<p><label> Il tuo nome <\/label><br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"your-name\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required form-control\" aria-required=\"true\" aria-invalid=\"false\" value=\"\" type=\"text\" name=\"your-name\" \/><\/span>\n\t\t\t<\/p>\n\t\t<\/div>\n\t\t<div class=\"col-6\">\n\t\t\t<p><label> Il tuo cognome <\/label><br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"your-surname\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required form-control\" aria-required=\"true\" aria-invalid=\"false\" value=\"\" type=\"text\" name=\"your-surname\" \/><\/span>\n\t\t\t<\/p>\n\t\t<\/div>\n\t\t<div class=\"col-6\">\n\t\t\t<p><label> La tua email <\/label><br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"your-email\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-email wpcf7-validates-as-required wpcf7-text wpcf7-validates-as-email form-control\" aria-required=\"true\" aria-invalid=\"false\" value=\"\" type=\"email\" name=\"your-email\" \/><\/span>\n\t\t\t<\/p>\n\t\t<\/div>\n\t\t<div class=\"col-6\">\n\t\t\t<p><label> Il tuo telefono <\/label><br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"tel-personale\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-tel wpcf7-validates-as-required wpcf7-text wpcf7-validates-as-tel form-control\" aria-required=\"true\" aria-invalid=\"false\" value=\"\" type=\"tel\" name=\"tel-personale\" \/><\/span>\n\t\t\t<\/p>\n\t\t<\/div>\n\t\t<div class=\"col-12\">\n\t\t\t<p><label> Il tuo messaggio (facoltativo) <\/label><br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"your-message\"><textarea cols=\"40\" rows=\"10\" maxlength=\"2000\" class=\"wpcf7-form-control wpcf7-textarea form-control\" aria-invalid=\"false\" name=\"your-message\"><\/textarea><\/span>\n\t\t\t<\/p>\n\t\t<\/div>\n\t\t<div class=\"col-12\" style=\"text-align:right\">\n\t\t\t<p><span class=\"wpcf7-form-control-wrap\" data-name=\"acceptance-privacy\"><span class=\"wpcf7-form-control wpcf7-acceptance\"><span class=\"wpcf7-list-item\"><label><input type=\"checkbox\" name=\"acceptance-privacy\" value=\"1\" aria-invalid=\"false\" \/><span class=\"wpcf7-list-item-label\">Ho letto e accetto la <a href=\"https:\/\/hotelbeltramonto.it\/privacy-policy\">Privacy Policy<\/a><\/span><\/label><\/span><\/span><\/span><br \/>\n<div class=\"cf7-cf-turnstile\" style=\"margin-top: 0px; margin-bottom: -15px;\"> <div id=\"cf-turnstile-cf7-4177726948\" class=\"cf-turnstile\" data-callback=\"turnstileCF7Callback\" data-sitekey=\"0x4AAAAAABV01mW2zJHzJXWz\" data-theme=\"light\" data-language=\"auto\" data-size=\"normal\" data-retry=\"auto\" data-retry-interval=\"1000\" data-action=\"contact-form-7\" data-appearance=\"always\"><\/div> <style>.wpcf7-submit { pointer-events: none; opacity: 0.5; }<\/style> <script>document.addEventListener(\"DOMContentLoaded\", function() { setTimeout(function(){ var e=document.getElementById(\"cf-turnstile-cf7-4177726948\"); e&&!e.innerHTML.trim()&&(turnstile.remove(\"#cf-turnstile-cf7-4177726948\"), turnstile.render(\"#cf-turnstile-cf7-4177726948\", {sitekey:\"0x4AAAAAABV01mW2zJHzJXWz\"})); }, 0); });<\/script> <br class=\"cf-turnstile-br cf-turnstile-br-cf7-4177726948\"> <style>#cf-turnstile-cf7-4177726948 { margin-left: -15px; }<\/style> <script>document.addEventListener(\"DOMContentLoaded\",function(){document.querySelectorAll('.wpcf7-form').forEach(function(e){e.addEventListener('submit',function(){if(document.getElementById('cf-turnstile-cf7-4177726948')){setTimeout(function(){turnstile.reset('#cf-turnstile-cf7-4177726948');},1000)}})})});<\/script> <\/div><br\/><input class=\"wpcf7-form-control wpcf7-submit has-spinner btn\" type=\"submit\" value=\"Invia\" \/>\n\t\t\t<\/p>\n\t\t<\/div>\n\t<\/div>\n<\/div><div class=\"wpcf7-response-output\" aria-hidden=\"true\"><\/div>\n<\/form>\n<\/div>\n<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_et_pb_use_builder":"on","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"class_list":["post-1922","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v25.3.1 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Offers - Hotel Bel Tramonto Park - Ischia<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/hotelbeltramonto.it\/en\/offers\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Offers - Hotel Bel Tramonto Park - Ischia\" \/>\n<meta property=\"og:description\" content=\"Discover our Offers\" \/>\n<meta property=\"og:url\" content=\"https:\/\/hotelbeltramonto.it\/en\/offers\/\" \/>\n<meta property=\"og:site_name\" content=\"Hotel Bel Tramonto Park - Ischia\" \/>\n<meta property=\"article:modified_time\" content=\"2026-03-11T11:50:11+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/hotelbeltramonto.it\/en\/offers\/\",\"url\":\"https:\/\/hotelbeltramonto.it\/en\/offers\/\",\"name\":\"Offers - Hotel Bel Tramonto Park - Ischia\",\"isPartOf\":{\"@id\":\"https:\/\/hotelbeltramonto.it\/en\/#website\"},\"datePublished\":\"2022-01-26T13:53:13+00:00\",\"dateModified\":\"2026-03-11T11:50:11+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/hotelbeltramonto.it\/en\/offers\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/hotelbeltramonto.it\/en\/offers\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/hotelbeltramonto.it\/en\/offers\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/hotelbeltramonto.it\/en\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Offers\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/hotelbeltramonto.it\/en\/#website\",\"url\":\"https:\/\/hotelbeltramonto.it\/en\/\",\"name\":\"Hotel Bel Tramonto Park - Ischia\",\"description\":\"Hotel Ischia Casamicciola\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/hotelbeltramonto.it\/en\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Offers - Hotel Bel Tramonto Park - Ischia","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/hotelbeltramonto.it\/en\/offers\/","og_locale":"en_US","og_type":"article","og_title":"Offers - Hotel Bel Tramonto Park - Ischia","og_description":"Discover our Offers","og_url":"https:\/\/hotelbeltramonto.it\/en\/offers\/","og_site_name":"Hotel Bel Tramonto Park - Ischia","article_modified_time":"2026-03-11T11:50:11+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/hotelbeltramonto.it\/en\/offers\/","url":"https:\/\/hotelbeltramonto.it\/en\/offers\/","name":"Offers - Hotel Bel Tramonto Park - Ischia","isPartOf":{"@id":"https:\/\/hotelbeltramonto.it\/en\/#website"},"datePublished":"2022-01-26T13:53:13+00:00","dateModified":"2026-03-11T11:50:11+00:00","breadcrumb":{"@id":"https:\/\/hotelbeltramonto.it\/en\/offers\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/hotelbeltramonto.it\/en\/offers\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/hotelbeltramonto.it\/en\/offers\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/hotelbeltramonto.it\/en\/"},{"@type":"ListItem","position":2,"name":"Offers"}]},{"@type":"WebSite","@id":"https:\/\/hotelbeltramonto.it\/en\/#website","url":"https:\/\/hotelbeltramonto.it\/en\/","name":"Hotel Bel Tramonto Park - Ischia","description":"Hotel Ischia Casamicciola","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/hotelbeltramonto.it\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"}]}},"_links":{"self":[{"href":"https:\/\/hotelbeltramonto.it\/en\/wp-json\/wp\/v2\/pages\/1922","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/hotelbeltramonto.it\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/hotelbeltramonto.it\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/hotelbeltramonto.it\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/hotelbeltramonto.it\/en\/wp-json\/wp\/v2\/comments?post=1922"}],"version-history":[{"count":3,"href":"https:\/\/hotelbeltramonto.it\/en\/wp-json\/wp\/v2\/pages\/1922\/revisions"}],"predecessor-version":[{"id":2478,"href":"https:\/\/hotelbeltramonto.it\/en\/wp-json\/wp\/v2\/pages\/1922\/revisions\/2478"}],"wp:attachment":[{"href":"https:\/\/hotelbeltramonto.it\/en\/wp-json\/wp\/v2\/media?parent=1922"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}